{"id":51912,"date":"2026-09-01T17:33:56","date_gmt":"2026-09-01T15:33:56","guid":{"rendered":"https:\/\/marbella-cribs.com\/?post_type=properties&#038;p=51912"},"modified":"2026-09-01T17:33:56","modified_gmt":"2026-09-01T15:33:56","slug":"auto-draft-94","status":"publish","type":"properties","link":"https:\/\/marbella-cribs.com\/es\/propiedades\/las-chapas-5-villa-contemporanea-en-marbella-este-mcg1907\/","featured_media":51962,"template":"","meta":{"_joinchat":[]},"urbanization":[],"area":[515],"city":[495],"feature":[30,135,120,8],"locations":[],"property-type":[156],"property-status":[10],"class_list":["post-51912","properties","type-properties","status-publish","has-post-thumbnail","hentry","area-marbella-east","city-marbella-ciudad","feature-modern","feature-parking-communal","feature-pool-communal","feature-terrace","property-type-villas","property-status-for-sale"],"aioseo_notices":[],"meta_box":{"ref":"MCG1907","price":"5875000","_is_from_price":"0","low_rental_price":"","high_rental_price":"","bedrooms":"5","bathrooms":"5","built":"837","plot":"1573","terrace":"255","more_info":[],"featured":"0","status":{"term_id":10,"name":"En Venta","slug":"for-sale","term_group":0,"term_taxonomy_id":10,"taxonomy":"property-status","description":"","parent":0,"count":288,"filter":"raw","term_order":"0","i18n_config":{"name":{"ts":{"en":"For Sale","es":"En Venta","fr":"A vendre"}}}},"type":{"term_id":156,"name":"Villas","slug":"villas","term_group":0,"term_taxonomy_id":156,"taxonomy":"property-type","description":"","parent":0,"count":165,"filter":"raw","term_order":"1","i18n_config":{"name":{"ts":{"en":"Villas"}}}},"city":{"term_id":495,"name":"Marbella","slug":"marbella-ciudad","term_group":0,"term_taxonomy_id":495,"taxonomy":"city","description":"La ciudad de Marbella es el centro de la ciudad de Marbella en la provincia de M\u00e1laga en Andaluc\u00eda en el sur de Espa\u00f1a. La ciudad de Marbella est\u00e1 a 9,8 km al este de Puerto Ban\u00fas ya 8,4 km de la Milla de Oro de Marbella. Marbella ciudad est\u00e1 a 30 minutos en coche del aeropuerto internacional de M\u00e1laga. La ciudad de Marbella es accesible por dos autopistas: la A7 y la Autopista del Sol (AP-7). La ciudad de Marbella es popular por su centro hist\u00f3rico, restaurantes t\u00edpicos andaluces y bares junto al mar.Las propiedades inmobiliarias en la ciudad de Marbella son el objetivo de los inversores extranjeros que desean comprar en la Costa del Sol. Los apartamentos, \u00e1ticos y d\u00faplex en venta en Marbella ciudad son buenas inversiones para obtener una alta rentabilidad por alquiler. Las propiedades en alquiler en la ciudad de Marbella tienen una gran demanda de turistas durante la temporada alta, ya que se encuentra en el centro.","parent":0,"count":256,"filter":"raw","term_order":"0","i18n_config":{"name":{"ts":{"en":"Marbella"}},"description":{"ts":{"en":"Marbella town is the city center of Marbella in the province of Malaga in Andalusia in southern Spain. Marbella town is 9.8 km east of Puerto Banus and 8.4 km from Marbella Golden Mile. Marbella town is 30 minutes drive from Malaga international airport. Marbella city is accessible by two highways: the A7 and the Autopista del Sol (AP-7). Marbella town is popular for its historic town centre, typical Andalusian restaurants and seaside bars. Real estate in Marbella town is the target of foreign investors wishing to buy on the Costa Del Sol. Apartments, penthouses and duplexes for sale in Marbella town are good investments to make high rental yields. Properties for rent in Marbella town are in high demand by tourists during high season as it is centrally located.","es":"La ciudad de Marbella es el centro de la ciudad de Marbella en la provincia de M\u00e1laga en Andaluc\u00eda en el sur de Espa\u00f1a. La ciudad de Marbella est\u00e1 a 9,8 km al este de Puerto Ban\u00fas ya 8,4 km de la Milla de Oro de Marbella. Marbella ciudad est\u00e1 a 30 minutos en coche del aeropuerto internacional de M\u00e1laga. La ciudad de Marbella es accesible por dos autopistas: la A7 y la Autopista del Sol (AP-7). La ciudad de Marbella es popular por su centro hist\u00f3rico, restaurantes t\u00edpicos andaluces y bares junto al mar.Las propiedades inmobiliarias en la ciudad de Marbella son el objetivo de los inversores extranjeros que desean comprar en la Costa del Sol. Los apartamentos, \u00e1ticos y d\u00faplex en venta en Marbella ciudad son buenas inversiones para obtener una alta rentabilidad por alquiler. Las propiedades en alquiler en la ciudad de Marbella tienen una gran demanda de turistas durante la temporada alta, ya que se encuentra en el centro.","fr":"Marbella ville est le centre ville de Marbella dans la province de Malaga en Andalousie dans le sud de l\u2019Espagne. Marbella ville est \u00e0 9,8 km \u00e0 l\u2019est de Puerto Banus et \u00e0 8,4 km de Marbella Golden Mile. Marbella ville est \u00e0 30 minutes en voiture de l'a\u00e9roport international de Malaga. Marbella ville est accesible par deux autoroutes : l\u2019A7 et l\u2019Autopista del Sol (AP-7). Marbella ville est populaire pour son centre ville historique, ses restaurants typiques andalous et ses bars en bord de mer. L\u2019immobilier \u00e0 Marbella ville est la cible des investisseurs \u00e9trangers qui souhaitent acheter sur la Costa Del Sol. Les appartements, penthouses et duplex \u00e0 vendre \u00e0 Marbella ville sont de bon investissements pour faire des rendements locatifs \u00e9lev\u00e9s. Les propri\u00e9t\u00e9s \u00e0 louer \u00e0 Marbella ville sont tr\u00e8s demand\u00e9s par les touristes durant la haute saison car c\u2019est une position centrale."},"ml":"[:en]Marbella town is the city center of Marbella in the province of Malaga in Andalusia in southern Spain. Marbella town is 9.8 km east of Puerto Banus and 8.4 km from Marbella Golden Mile. Marbella town is 30 minutes drive from Malaga international airport. Marbella city is accessible by two highways: the A7 and the Autopista del Sol (AP-7). Marbella town is popular for its historic town centre, typical Andalusian restaurants and seaside bars. Real estate in Marbella town is the target of foreign investors wishing to buy on the Costa Del Sol. Apartments, penthouses and duplexes for sale in Marbella town are good investments to make high rental yields. Properties for rent in Marbella town are in high demand by tourists during high season as it is centrally located.[:es]La ciudad de Marbella es el centro de la ciudad de Marbella en la provincia de M\u00e1laga en Andaluc\u00eda en el sur de Espa\u00f1a. La ciudad de Marbella est\u00e1 a 9,8 km al este de Puerto Ban\u00fas ya 8,4 km de la Milla de Oro de Marbella. Marbella ciudad est\u00e1 a 30 minutos en coche del aeropuerto internacional de M\u00e1laga. La ciudad de Marbella es accesible por dos autopistas: la A7 y la Autopista del Sol (AP-7). La ciudad de Marbella es popular por su centro hist\u00f3rico, restaurantes t\u00edpicos andaluces y bares junto al mar.Las propiedades inmobiliarias en la ciudad de Marbella son el objetivo de los inversores extranjeros que desean comprar en la Costa del Sol. Los apartamentos, \u00e1ticos y d\u00faplex en venta en Marbella ciudad son buenas inversiones para obtener una alta rentabilidad por alquiler. Las propiedades en alquiler en la ciudad de Marbella tienen una gran demanda de turistas durante la temporada alta, ya que se encuentra en el centro.[:fr]Marbella ville est le centre ville de Marbella dans la province de Malaga en Andalousie dans le sud de l\u2019Espagne. Marbella ville est \u00e0 9,8 km \u00e0 l\u2019est de Puerto Banus et \u00e0 8,4 km de Marbella Golden Mile. Marbella ville est \u00e0 30 minutes en voiture de l'a\u00e9roport international de Malaga. Marbella ville est accesible par deux autoroutes : l\u2019A7 et l\u2019Autopista del Sol (AP-7). Marbella ville est populaire pour son centre ville historique, ses restaurants typiques andalous et ses bars en bord de mer. L\u2019immobilier \u00e0 Marbella ville est la cible des investisseurs \u00e9trangers qui souhaitent acheter sur la Costa Del Sol. Les appartements, penthouses et duplex \u00e0 vendre \u00e0 Marbella ville sont de bon investissements pour faire des rendements locatifs \u00e9lev\u00e9s. Les propri\u00e9t\u00e9s \u00e0 louer \u00e0 Marbella ville sont tr\u00e8s demand\u00e9s par les touristes durant la haute saison car c\u2019est une position centrale.[:]"}}},"area":{"term_id":515,"name":"Marbella Este","slug":"marbella-east","term_group":0,"term_taxonomy_id":515,"taxonomy":"area","description":"Marbella Este es una zona de Marbella en la provincia de M\u00e1laga en Andaluc\u00eda en el sur de Espa\u00f1a. Marbella Este se encuentra a 11 km al este del centro de la ciudad de Marbella ya 20 km al este de Puerto Ban\u00fas. Marbella Este se encuentra a 30 minutos en coche del Aeropuerto Internacional de M\u00e1laga. Marbella Este es accesible por dos autov\u00edas: la A7 y la Autopista del Sol (AP-7). Marbella Este es popular por tener las mejores playas del \u00e1rea de Marbella, sus campos de golf y sus zonas residenciales. Elviria, Marbesa y Hacienda Las Chapas son las zonas m\u00e1s prestigiosas de Marbella Este. Las propiedades en venta en Marbella Est son villas, apartamentos y \u00e1ticos con vistas al mar.","parent":0,"count":35,"filter":"raw","term_order":"0","i18n_config":{"name":{"ts":{"en":"Marbella East","es":"Marbella Este","fr":"Marbella Est"}},"description":{"ts":{"en":"Marbella East is an area of \u200b\u200bMarbella in the province of Malaga in Andalusia in southern Spain. Marbella East is 11 km east of Marbella city center and 20 km east of Puerto Banus. Marbella East is a 30 minute drive from Malaga International Airport. Marbella East is accessible by two highways: the A7 and the Autopista del Sol (AP-7). Marbella East is popular for having the best beaches in the Marbella area, its golf courses and its residential areas. Elviria, Marbesa and Hacienda Las Chapas are the most prestigious areas of Marbella East. The properties for sale in Marbella East are villas, apartments and penthouses with sea views.","es":"Marbella Este es una zona de Marbella en la provincia de M\u00e1laga en Andaluc\u00eda en el sur de Espa\u00f1a. Marbella Este se encuentra a 11 km al este del centro de la ciudad de Marbella ya 20 km al este de Puerto Ban\u00fas. Marbella Este se encuentra a 30 minutos en coche del Aeropuerto Internacional de M\u00e1laga. Marbella Este es accesible por dos autov\u00edas: la A7 y la Autopista del Sol (AP-7). Marbella Este es popular por tener las mejores playas del \u00e1rea de Marbella, sus campos de golf y sus zonas residenciales. Elviria, Marbesa y Hacienda Las Chapas son las zonas m\u00e1s prestigiosas de Marbella Este. Las propiedades en venta en Marbella Est son villas, apartamentos y \u00e1ticos con vistas al mar.","fr":"Marbella Est est une zone de Marbella dans la province de Malaga en Andalousie dans le sud de l'Espagne. Marbella Est est \u00e0 11 km \u00e0 l\u2019est du centre-ville de Marbella et \u00e0 20 km \u00e0 l'est de Puerto Banus. Marbella Est est \u00e0 30 minutes en voiture de l'a\u00e9roport international de Malaga. Marbella Est est accesible par deux autoroutes : l\u2019A7 et l\u2019Autopista del Sol (AP-7). Marbella Est est populaire pour avoir les plus belles plages de la r\u00e9gion de Marbella, ses terrains de golf et ses quartiers r\u00e9sidentiels. Elviria, Marbesa et Hacienda Las Chapas sont les zones les plus prestigieuses de Marbella Est. Les propri\u00e9t\u00e9s \u00e0 vendre \u00e0 Marbella Est sont des villas,des appartements et des penthouses avec vue mer."},"ml":"[:en]Marbella East is an area of \u200b\u200bMarbella in the province of Malaga in Andalusia in southern Spain. Marbella East is 11 km east of Marbella city center and 20 km east of Puerto Banus. Marbella East is a 30 minute drive from Malaga International Airport. Marbella East is accessible by two highways: the A7 and the Autopista del Sol (AP-7). Marbella East is popular for having the best beaches in the Marbella area, its golf courses and its residential areas. Elviria, Marbesa and Hacienda Las Chapas are the most prestigious areas of Marbella East. The properties for sale in Marbella East are villas, apartments and penthouses with sea views.[:es]Marbella Este es una zona de Marbella en la provincia de M\u00e1laga en Andaluc\u00eda en el sur de Espa\u00f1a. Marbella Este se encuentra a 11 km al este del centro de la ciudad de Marbella ya 20 km al este de Puerto Ban\u00fas. Marbella Este se encuentra a 30 minutos en coche del Aeropuerto Internacional de M\u00e1laga. Marbella Este es accesible por dos autov\u00edas: la A7 y la Autopista del Sol (AP-7). Marbella Este es popular por tener las mejores playas del \u00e1rea de Marbella, sus campos de golf y sus zonas residenciales. Elviria, Marbesa y Hacienda Las Chapas son las zonas m\u00e1s prestigiosas de Marbella Este. Las propiedades en venta en Marbella Est son villas, apartamentos y \u00e1ticos con vistas al mar.[:fr]Marbella Est est une zone de Marbella dans la province de Malaga en Andalousie dans le sud de l'Espagne. Marbella Est est \u00e0 11 km \u00e0 l\u2019est du centre-ville de Marbella et \u00e0 20 km \u00e0 l'est de Puerto Banus. Marbella Est est \u00e0 30 minutes en voiture de l'a\u00e9roport international de Malaga. Marbella Est est accesible par deux autoroutes : l\u2019A7 et l\u2019Autopista del Sol (AP-7). Marbella Est est populaire pour avoir les plus belles plages de la r\u00e9gion de Marbella, ses terrains de golf et ses quartiers r\u00e9sidentiels. Elviria, Marbesa et Hacienda Las Chapas sont les zones les plus prestigieuses de Marbella Est. Les propri\u00e9t\u00e9s \u00e0 vendre \u00e0 Marbella Est sont des villas,des appartements et des penthouses avec vue mer.[:]"}}},"subarea":false,"map":"Marbella Las Chapas","zoom":"","features":[{"term_id":30,"name":"Propiedades Modernas","slug":"modern","term_group":0,"term_taxonomy_id":30,"taxonomy":"feature","description":"Las villas modernas en Marbella son \u00fanicas por su apariencia exterior. Estas villas en venta en Marbella son ideales porque sus construcciones se han sometido a m\u00e9todos y materiales modernos. Los apartamentos de lujo en Marbella tambi\u00e9n son modernos y ofrecen instalaciones de \u00faltima generaci\u00f3n.","parent":0,"count":263,"filter":"raw","term_order":"5","i18n_config":{"name":{"ts":{"en":"Modern Properties","es":"Propiedades Modernas","fr":"Propri\u00e9t\u00e9s Modernes"}},"description":{"ts":{"en":"Modern villas in Marbella are unique for their outward appearance. These villas for sale in Marbella are ideal because their constructions have been subjected to modern methods and materials. The luxury apartments in Marbella are also modern and offer state-of-the-art facilities.","es":"Las villas modernas en Marbella son \u00fanicas por su apariencia exterior. Estas villas en venta en Marbella son ideales porque sus construcciones se han sometido a m\u00e9todos y materiales modernos. Los apartamentos de lujo en Marbella tambi\u00e9n son modernos y ofrecen instalaciones de \u00faltima generaci\u00f3n.","fr":"Les villas modernes \u00e0 Marbella sont uniques pour leur apparence ext\u00e9rieure. Ces villas \u00e0 vendre \u00e0 Marbella sont id\u00e9ales car leurs constructions ont \u00e9t\u00e9 soumises \u00e0 des m\u00e9thodes et des mat\u00e9riaux modernes. Les luxueux appartements \u00e0 Marbella sont aussi modernes et proposent des installations de derni\u00e8re technologie."},"ml":"[:en]Modern villas in Marbella are unique for their outward appearance. These villas for sale in Marbella are ideal because their constructions have been subjected to modern methods and materials. The luxury apartments in Marbella are also modern and offer state-of-the-art facilities.[:es]Las villas modernas en Marbella son \u00fanicas por su apariencia exterior. Estas villas en venta en Marbella son ideales porque sus construcciones se han sometido a m\u00e9todos y materiales modernos. Los apartamentos de lujo en Marbella tambi\u00e9n son modernos y ofrecen instalaciones de \u00faltima generaci\u00f3n.[:fr]Les villas modernes \u00e0 Marbella sont uniques pour leur apparence ext\u00e9rieure. Ces villas \u00e0 vendre \u00e0 Marbella sont id\u00e9ales car leurs constructions ont \u00e9t\u00e9 soumises \u00e0 des m\u00e9thodes et des mat\u00e9riaux modernes. Les luxueux appartements \u00e0 Marbella sont aussi modernes et proposent des installations de derni\u00e8re technologie.[:]"}}},{"term_id":135,"name":"Aparcamiento privado","slug":"parking-communal","term_group":0,"term_taxonomy_id":135,"taxonomy":"feature","description":"","parent":0,"count":244,"filter":"raw","term_order":"9","i18n_config":{"name":{"ts":{"en":"Private parking","es":"Aparcamiento privado","fr":"Parking priv\u00e9"}}}},{"term_id":120,"name":"Piscina","slug":"pool-communal","term_group":0,"term_taxonomy_id":120,"taxonomy":"feature","description":"","parent":0,"count":360,"filter":"raw","term_order":"11","i18n_config":{"name":{"ts":{"en":"Pool","es":"Piscina","fr":"Piscine"}}}},{"term_id":8,"name":"Terraza","slug":"terrace","term_group":0,"term_taxonomy_id":8,"taxonomy":"feature","description":"","parent":0,"count":371,"filter":"raw","term_order":"18","i18n_config":{"name":{"ts":{"en":"Terrace","es":"Terraza","fr":"Terrasse"}}}}],"gallery":[{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella50.jpg","filesize":1096935,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella50-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":197702,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella50-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51962","name":"villa-for-sale-in-las-chapas-Marbella50.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella50.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella50-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella50.jpg","title":"villa for sale in las chapas Marbella50","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella1.jpg","filesize":462410,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella1-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":93478,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella1-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51913","name":"villa-for-sale-in-las-chapas-Marbella1.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella1.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella1-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella1.jpg","title":"villa for sale in las chapas Marbella1","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella49.jpg","filesize":1440278,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella49-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":260181,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella49-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51961","name":"villa-for-sale-in-las-chapas-Marbella49.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella49.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella49-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella49.jpg","title":"villa for sale in las chapas Marbella49","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella37.jpg","filesize":803577,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella37-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":147045,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella37-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51949","name":"villa-for-sale-in-las-chapas-Marbella37.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella37.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella37-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella37.jpg","title":"villa for sale in las chapas Marbella37","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella19.jpg","filesize":487184,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella19-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":111395,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella19-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51931","name":"villa-for-sale-in-las-chapas-Marbella19.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella19.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella19-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella19.jpg","title":"villa for sale in las chapas Marbella19","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella20.jpg","filesize":448958,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella20-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":101574,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella20-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51932","name":"villa-for-sale-in-las-chapas-Marbella20.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella20.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella20-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella20.jpg","title":"villa for sale in las chapas Marbella20","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella2.jpg","filesize":441332,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella2-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":92937,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella2-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51914","name":"villa-for-sale-in-las-chapas-Marbella2.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella2.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella2-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella2.jpg","title":"villa for sale in las chapas Marbella2","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella3.jpg","filesize":506522,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella3-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":100308,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella3-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51915","name":"villa-for-sale-in-las-chapas-Marbella3.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella3.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella3-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella3.jpg","title":"villa for sale in las chapas Marbella3","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella4.jpg","filesize":494926,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella4-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":104158,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella4-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51916","name":"villa-for-sale-in-las-chapas-Marbella4.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella4.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella4-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella4.jpg","title":"villa for sale in las chapas Marbella4","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella6.jpg","filesize":891091,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella6-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":161928,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella6-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51918","name":"villa-for-sale-in-las-chapas-Marbella6.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella6.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella6-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella6.jpg","title":"villa for sale in las chapas Marbella6","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella7.jpg","filesize":627919,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella7-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":129701,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella7-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51919","name":"villa-for-sale-in-las-chapas-Marbella7.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella7.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella7-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella7.jpg","title":"villa for sale in las chapas Marbella7","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella8.jpg","filesize":386673,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella8-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":82216,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella8-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51920","name":"villa-for-sale-in-las-chapas-Marbella8.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella8.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella8-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella8.jpg","title":"villa for sale in las chapas Marbella8","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella9.jpg","filesize":525768,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella9-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":102331,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella9-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51921","name":"villa-for-sale-in-las-chapas-Marbella9.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella9.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella9-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella9.jpg","title":"villa for sale in las chapas Marbella9","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella10.jpg","filesize":584891,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella10-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":113148,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella10-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51922","name":"villa-for-sale-in-las-chapas-Marbella10.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella10.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella10-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella10.jpg","title":"villa for sale in las chapas Marbella10","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella11.jpg","filesize":551454,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella11-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":99062,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella11-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51923","name":"villa-for-sale-in-las-chapas-Marbella11.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella11.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella11-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella11.jpg","title":"villa for sale in las chapas Marbella11","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella12.jpg","filesize":365011,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella12-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":81277,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella12-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51924","name":"villa-for-sale-in-las-chapas-Marbella12.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella12.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella12-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella12.jpg","title":"villa for sale in las chapas Marbella12","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella13.jpg","filesize":258787,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella13-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":50698,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella13-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51925","name":"villa-for-sale-in-las-chapas-Marbella13.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella13.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella13-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella13.jpg","title":"villa for sale in las chapas Marbella13","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella14.jpg","filesize":559891,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella14-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":119076,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella14-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51926","name":"villa-for-sale-in-las-chapas-Marbella14.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella14.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella14-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella14.jpg","title":"villa for sale in las chapas Marbella14","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella15.jpg","filesize":499444,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella15-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":120318,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella15-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51927","name":"villa-for-sale-in-las-chapas-Marbella15.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella15.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella15-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella15.jpg","title":"villa for sale in las chapas Marbella15","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella16.jpg","filesize":476494,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella16-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":103065,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella16-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51928","name":"villa-for-sale-in-las-chapas-Marbella16.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella16.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella16-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella16.jpg","title":"villa for sale in las chapas Marbella16","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella17.jpg","filesize":572197,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella17-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":126184,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella17-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51929","name":"villa-for-sale-in-las-chapas-Marbella17.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella17.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella17-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella17.jpg","title":"villa for sale in las chapas Marbella17","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella18.jpg","filesize":428588,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella18-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":91090,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella18-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51930","name":"villa-for-sale-in-las-chapas-Marbella18.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella18.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella18-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella18.jpg","title":"villa for sale in las chapas Marbella18","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella21.jpg","filesize":535790,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella21-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":107030,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella21-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51933","name":"villa-for-sale-in-las-chapas-Marbella21.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella21.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella21-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella21.jpg","title":"villa for sale in las chapas Marbella21","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella22.jpg","filesize":429075,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella22-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":98489,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella22-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51934","name":"villa-for-sale-in-las-chapas-Marbella22.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella22.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella22-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella22.jpg","title":"villa for sale in las chapas Marbella22","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella23.jpg","filesize":542639,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella23-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":111500,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella23-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51935","name":"villa-for-sale-in-las-chapas-Marbella23.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella23.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella23-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella23.jpg","title":"villa for sale in las chapas Marbella23","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella24.jpg","filesize":558116,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella24-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":122516,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella24-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51936","name":"villa-for-sale-in-las-chapas-Marbella24.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella24.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella24-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella24.jpg","title":"villa for sale in las chapas Marbella24","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella25.jpg","filesize":471017,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella25-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":105715,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella25-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51937","name":"villa-for-sale-in-las-chapas-Marbella25.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella25.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella25-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella25.jpg","title":"villa for sale in las chapas Marbella25","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella26.jpg","filesize":502730,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella26-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":106990,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella26-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51938","name":"villa-for-sale-in-las-chapas-Marbella26.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella26.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella26-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella26.jpg","title":"villa for sale in las chapas Marbella26","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella27.jpg","filesize":435748,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella27-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":103957,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella27-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51939","name":"villa-for-sale-in-las-chapas-Marbella27.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella27.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella27-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella27.jpg","title":"villa for sale in las chapas Marbella27","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella28.jpg","filesize":511736,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella28-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":106919,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella28-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51940","name":"villa-for-sale-in-las-chapas-Marbella28.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella28.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella28-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella28.jpg","title":"villa for sale in las chapas Marbella28","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella29.jpg","filesize":788492,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella29-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":173022,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella29-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51941","name":"villa-for-sale-in-las-chapas-Marbella29.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella29.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella29-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella29.jpg","title":"villa for sale in las chapas Marbella29","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella30.jpg","filesize":750226,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella30-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":148767,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella30-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51942","name":"villa-for-sale-in-las-chapas-Marbella30.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella30.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella30-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella30.jpg","title":"villa for sale in las chapas Marbella30","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella31.jpg","filesize":805133,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella31-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":162737,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella31-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51943","name":"villa-for-sale-in-las-chapas-Marbella31.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella31.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella31-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella31.jpg","title":"villa for sale in las chapas Marbella31","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella32.jpg","filesize":1260492,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella32-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":229181,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella32-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51944","name":"villa-for-sale-in-las-chapas-Marbella32.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella32.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella32-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella32.jpg","title":"villa for sale in las chapas Marbella32","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella33.jpg","filesize":1096204,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella33-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":185269,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella33-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51945","name":"villa-for-sale-in-las-chapas-Marbella33.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella33.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella33-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella33.jpg","title":"villa for sale in las chapas Marbella33","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella34.jpg","filesize":1151818,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella34-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":202432,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella34-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51946","name":"villa-for-sale-in-las-chapas-Marbella34.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella34.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella34-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella34.jpg","title":"villa for sale in las chapas Marbella34","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella35.jpg","filesize":868675,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella35-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":156194,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella35-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51947","name":"villa-for-sale-in-las-chapas-Marbella35.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella35.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella35-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella35.jpg","title":"villa for sale in las chapas Marbella35","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella5.jpg","filesize":935187,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella5-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":158028,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella5-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51917","name":"villa-for-sale-in-las-chapas-Marbella5.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella5.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella5-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella5.jpg","title":"villa for sale in las chapas Marbella5","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella36.jpg","filesize":686187,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella36-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":150061,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella36-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51948","name":"villa-for-sale-in-las-chapas-Marbella36.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella36.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella36-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella36.jpg","title":"villa for sale in las chapas Marbella36","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella38.jpg","filesize":970021,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella38-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":188847,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella38-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51950","name":"villa-for-sale-in-las-chapas-Marbella38.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella38.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella38-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella38.jpg","title":"villa for sale in las chapas Marbella38","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella39.jpg","filesize":802765,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella39-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":185990,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella39-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51951","name":"villa-for-sale-in-las-chapas-Marbella39.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella39.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella39-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella39.jpg","title":"villa for sale in las chapas Marbella39","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella40.jpg","filesize":745871,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella40-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":150630,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella40-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51952","name":"villa-for-sale-in-las-chapas-Marbella40.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella40.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella40-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella40.jpg","title":"villa for sale in las chapas Marbella40","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella41.jpg","filesize":745982,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella41-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":146256,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella41-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51953","name":"villa-for-sale-in-las-chapas-Marbella41.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella41.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella41-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella41.jpg","title":"villa for sale in las chapas Marbella41","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella42.jpg","filesize":453242,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella42-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":101246,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella42-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51954","name":"villa-for-sale-in-las-chapas-Marbella42.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella42.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella42-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella42.jpg","title":"villa for sale in las chapas Marbella42","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella43.jpg","filesize":835671,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella43-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":156885,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella43-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51955","name":"villa-for-sale-in-las-chapas-Marbella43.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella43.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella43-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella43.jpg","title":"villa for sale in las chapas Marbella43","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella44.jpg","filesize":983980,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella44-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":193194,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella44-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51956","name":"villa-for-sale-in-las-chapas-Marbella44.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella44.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella44-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella44.jpg","title":"villa for sale in las chapas Marbella44","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella45.jpg","filesize":864335,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella45-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":168498,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella45-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51957","name":"villa-for-sale-in-las-chapas-Marbella45.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella45.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella45-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella45.jpg","title":"villa for sale in las chapas Marbella45","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella46.jpg","filesize":1383564,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella46-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":254566,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella46-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51958","name":"villa-for-sale-in-las-chapas-Marbella46.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella46.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella46-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella46.jpg","title":"villa for sale in las chapas Marbella46","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella47.jpg","filesize":1354053,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella47-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":244887,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella47-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51959","name":"villa-for-sale-in-las-chapas-Marbella47.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella47.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella47-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella47.jpg","title":"villa for sale in las chapas Marbella47","caption":"","description":"","alt":"","srcset":false},{"width":700,"height":700,"file":"2026\/09\/villa-for-sale-in-las-chapas-Marbella48.jpg","filesize":1435231,"sizes":{"thumbnail":{"file":"villa-for-sale-in-las-chapas-Marbella48-700x700.jpg","width":700,"height":700,"mime-type":"image\/jpeg","filesize":254211,"url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella48-700x700.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"51960","name":"villa-for-sale-in-las-chapas-Marbella48.jpg","path":"\/home\/marbellacribs\/public_html\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella48.jpg","url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella48-700x700.jpg","full_url":"https:\/\/marbella-cribs.com\/wp-content\/uploads\/2026\/09\/villa-for-sale-in-las-chapas-Marbella48.jpg","title":"villa for sale in las chapas Marbella48","caption":"","description":"","alt":"","srcset":false}],"video":"","pdf":"","external":[],"title_en":"Las Chapas 5 \u2013 Contemporary Villa in Marbella East","content_en":"Las Chapas 5 is a beautifully designed contemporary villa set in the sought-after residential area of Las Chapas, Marbella East. Combining modern architecture with warm natural elements, the property has been thoughtfully designed around effortless indoor-outdoor living and the relaxed Mediterranean lifestyle.\r\n\r\nThe main level is centred around a bright and spacious open-plan living area, where the lounge, dining space and modern kitchen flow seamlessly together. Floor-to-ceiling sliding glass doors open directly onto the terraces, landscaped gardens and swimming pool, creating a natural extension of the interior living spaces. Clean architectural lines, warm wood finishes and abundant natural light give the home an elegant yet welcoming atmosphere.\r\n\r\nThe villa offers a selection of beautifully appointed guest bedrooms alongside a generous master suite, all designed to maximise privacy, comfort and views of the surrounding greenery. The master suite features a spacious ensuite bathroom with a freestanding bathtub, double vanity and refined wooden architectural detailing, creating a sense of separation while preserving the open and contemporary character of the space.\r\n\r\nA dedicated lower level adds another dimension to the property, offering an impressive entertainment area designed for relaxation and socialising. Complete with a comfortable lounge, bar and pool table, it provides the perfect setting for entertaining guests while allowing the main floor to retain its convenient one-level living concept.\r\n\r\nOutside, Las Chapas 5 has been designed to make the most of Marbella\u2019s year-round climate. Mature palm trees and carefully landscaped gardens surround the swimming pool, which forms the centrepiece of the outdoor area. Stepping stones, sunbathing areas, a covered dining terrace and a striking sunken firepit lounge with integrated lighting create multiple spaces for relaxing and entertaining throughout the day and into the evening.\r\n\r\nThe property also benefits from an excellent location in Marbella East. The beaches of Las Chapas and Elviria are less than five minutes away by car, while some of the area\u2019s best-known beach clubs, including Nikki Beach, Dune Beach and Bono Beach, are all within easy reach. For everyday convenience, a supermarket is also located approximately five minutes away on foot.\r\n\r\nCombining contemporary design, generous entertainment spaces, privacy and proximity to the beach, Las Chapas 5 offers an exceptional lifestyle opportunity in one of Marbella East\u2019s most desirable residential areas.\r\n","title_es":"Las Chapas 5 \u2013 Villa contempor\u00e1nea en Marbella Este-mcg1907","content_es":"Las Chapas 5 es una espectacular villa contempor\u00e1nea situada en la codiciada zona residencial de Las Chapas, en Marbella Este. Combinando una arquitectura moderna con c\u00e1lidos elementos naturales, la propiedad ha sido cuidadosamente dise\u00f1ada para crear una perfecta conexi\u00f3n entre los espacios interiores y exteriores, reflejando a la perfecci\u00f3n el estilo de vida mediterr\u00e1neo.\r\n\r\nLa planta principal gira en torno a una amplia y luminosa zona de concepto abierto, donde sal\u00f3n, comedor y cocina contempor\u00e1nea se integran de manera fluida. Grandes puertas correderas de cristal de suelo a techo se abren directamente hacia las terrazas, los jardines paisaj\u00edsticos y la piscina, creando una prolongaci\u00f3n natural de los espacios interiores. Las l\u00edneas depuradas, los acabados en madera y la abundante luz natural aportan a la vivienda un ambiente elegante, sofisticado y acogedor.\r\n\r\nLa villa cuenta con varias habitaciones de invitados cuidadosamente dise\u00f1adas, adem\u00e1s de una amplia suite principal, todas ellas pensadas para ofrecer privacidad, confort y agradables vistas a la vegetaci\u00f3n que rodea la propiedad. La suite principal dispone de un espacioso cuarto de ba\u00f1o en suite con ba\u00f1era exenta, doble lavabo y elegantes detalles arquitect\u00f3nicos en madera que aportan privacidad sin renunciar al car\u00e1cter abierto y contempor\u00e1neo del espacio.\r\n\r\nLa planta inferior a\u00f1ade una dimensi\u00f3n adicional a la propiedad con una impresionante zona dedicada al ocio y al entretenimiento. Equipada con una c\u00f3moda zona de estar, bar y mesa de billar, ofrece el ambiente perfecto para relajarse y disfrutar con familiares y amigos, manteniendo al mismo tiempo la comodidad de tener las principales zonas de la vivienda distribuidas en una sola planta.\r\n\r\nLos exteriores de Las Chapas 5 han sido dise\u00f1ados para disfrutar al m\u00e1ximo del privilegiado clima de Marbella durante todo el a\u00f1o. Palmeras maduras y cuidados jardines rodean la piscina, que se convierte en el elemento central de la zona exterior. Diferentes \u00e1reas para tomar el sol y relajarse, una terraza cubierta con comedor exterior y una espectacular zona de estar hundida con firepit e iluminaci\u00f3n integrada crean distintos ambientes para disfrutar y recibir invitados tanto durante el d\u00eda como por la noche.\r\n\r\nLa propiedad disfruta adem\u00e1s de una excelente ubicaci\u00f3n en Marbella Este. Las playas de Las Chapas y Elviria se encuentran a menos de cinco minutos en coche, mientras que algunos de los beach clubs m\u00e1s conocidos de la zona, como Nikki Beach, Dune Beach y Bono Beach, est\u00e1n a poca distancia. Para mayor comodidad en el d\u00eda a d\u00eda, tambi\u00e9n hay un supermercado situado a aproximadamente cinco minutos a pie de la villa.\r\n\r\nCombinando dise\u00f1o contempor\u00e1neo, amplios espacios de entretenimiento, privacidad y proximidad a la playa, Las Chapas 5 ofrece una excepcional oportunidad para disfrutar del estilo de vida de Marbella en una de las zonas residenciales m\u00e1s deseadas de Marbella Este.\r\n","title_fr":"Las Chapas 5 \u2013 Villa contemporaine \u00e0 Marbella Est","content_fr":"Las Chapas 5 est une superbe villa contemporaine situ\u00e9e dans le quartier r\u00e9sidentiel tr\u00e8s recherch\u00e9 de Las Chapas, \u00e0 Marbella Est. Associant architecture moderne et mat\u00e9riaux naturels chaleureux, la propri\u00e9t\u00e9 a \u00e9t\u00e9 pens\u00e9e autour d\u2019une parfaite continuit\u00e9 entre les espaces int\u00e9rieurs et ext\u00e9rieurs, en harmonie avec l\u2019art de vivre m\u00e9diterran\u00e9en.\r\n\r\nLe niveau principal s\u2019articule autour d\u2019un vaste et lumineux espace de vie ouvert, r\u00e9unissant salon, salle \u00e0 manger et cuisine contemporaine dans une atmosph\u00e8re fluide et \u00e9l\u00e9gante. De grandes baies vitr\u00e9es coulissantes toute hauteur s\u2019ouvrent directement sur les terrasses, les jardins paysagers et la piscine, prolongeant naturellement les espaces de vie vers l\u2019ext\u00e9rieur. Les lignes \u00e9pur\u00e9es, les finitions en bois et l\u2019abondance de lumi\u00e8re naturelle conf\u00e8rent \u00e0 l\u2019ensemble une ambiance \u00e0 la fois sophistiqu\u00e9e et chaleureuse.\r\n\r\nLa villa dispose de plusieurs chambres d\u2019amis soigneusement am\u00e9nag\u00e9es ainsi que d\u2019une g\u00e9n\u00e9reuse suite parentale, toutes con\u00e7ues pour offrir intimit\u00e9, confort et vues agr\u00e9ables sur la v\u00e9g\u00e9tation environnante. La suite principale b\u00e9n\u00e9ficie d\u2019une spacieuse salle de bains en suite avec baignoire \u00eelot, double vasque et \u00e9l\u00e9gants \u00e9l\u00e9ments architecturaux en bois, apportant de l\u2019intimit\u00e9 tout en pr\u00e9servant le caract\u00e8re ouvert et contemporain de l\u2019espace.\r\n\r\nLe niveau inf\u00e9rieur apporte une dimension suppl\u00e9mentaire \u00e0 la propri\u00e9t\u00e9 avec un superbe espace d\u00e9di\u00e9 aux loisirs et \u00e0 la d\u00e9tente. Il comprend un salon confortable, un bar et un billard, offrant un cadre id\u00e9al pour recevoir famille et amis, tout en permettant de conserver l\u2019essentiel des espaces de vie sur un seul niveau.\r\n\r\n\u00c0 l\u2019ext\u00e9rieur, Las Chapas 5 a \u00e9t\u00e9 con\u00e7ue pour profiter pleinement du climat privil\u00e9gi\u00e9 de Marbella tout au long de l\u2019ann\u00e9e. Des palmiers matures et des jardins soigneusement paysag\u00e9s entourent la piscine, v\u00e9ritable pi\u00e8ce ma\u00eetresse des espaces ext\u00e9rieurs. Des zones de d\u00e9tente et de bains de soleil, une terrasse couverte avec espace repas ainsi qu\u2019un spectaculaire salon en contrebas avec brasero et \u00e9clairage int\u00e9gr\u00e9 offrent diff\u00e9rents espaces pour se d\u00e9tendre et recevoir, de jour comme de nuit.\r\n\r\nLa propri\u00e9t\u00e9 b\u00e9n\u00e9ficie \u00e9galement d\u2019un excellent emplacement \u00e0 Marbella Est. Les plages de Las Chapas et d\u2019Elviria se trouvent \u00e0 moins de cinq minutes en voiture, tandis que plusieurs des beach clubs les plus r\u00e9put\u00e9s de la r\u00e9gion, notamment Nikki Beach, Dune Beach et Bono Beach, sont facilement accessibles. Pour encore plus de confort au quotidien, un supermarch\u00e9 se trouve \u00e9galement \u00e0 environ cinq minutes \u00e0 pied de la villa.\r\n\r\nAssociant design contemporain, g\u00e9n\u00e9reux espaces de r\u00e9ception, intimit\u00e9 et proximit\u00e9 imm\u00e9diate de la plage, Las Chapas 5 repr\u00e9sente une superbe opportunit\u00e9 de profiter pleinement du lifestyle de Marbella dans l\u2019un des quartiers r\u00e9sidentiels les plus pris\u00e9s de Marbella Est.\r\n"},"_links":{"self":[{"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/properties\/51912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/types\/properties"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/media\/51962"}],"wp:attachment":[{"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/media?parent=51912"}],"wp:term":[{"taxonomy":"urbanization","embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/urbanization?post=51912"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/area?post=51912"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/city?post=51912"},{"taxonomy":"feature","embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/feature?post=51912"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/locations?post=51912"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/property-type?post=51912"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/marbella-cribs.com\/es\/wp-json\/wp\/v2\/property-status?post=51912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}